{"id":5952,"date":"2022-09-29T12:55:16","date_gmt":"2022-09-29T12:55:16","guid":{"rendered":"http:\/\/bonezzi.it\/product\/ingrassatore-automatico-ricaricabile-de\/"},"modified":"2024-04-09T15:24:10","modified_gmt":"2024-04-09T15:24:10","slug":"681-220a-ingrassatore-automatico-ricaricabile-de","status":"publish","type":"product","link":"https:\/\/bonezzi.it\/de\/produkt\/681-220a-ingrassatore-automatico-ricaricabile-de\/","title":{"rendered":"Ingrassatore automatico ricaricabile"},"content":{"rendered":"<p>SLOT GREASE\u00ae eroga il grasso in modo automatico in base alla richiesta del macchinario ed in funzione al tipo di molla, alla temperatura, al tipo di grasso NLGI e alle condizioni di esercizio. DURATA EROGAZIONE GRASSO: 1, 3, 6, 12 mesi. Contenitore da 220 ml costruito in *Lexan\u00ae trasparente ad alta resistenza meccanica, chimica e termica. Visualizza il consumo e consente il controllo a distanza grazie alla totale trasparenza. Attivazione immediata. Nessuna batteria o gas. Installabile al chiuso, all&#8217;aperto, a distanza, al contrario, sott\u2019acqua, in punti pericolosi e scomodi. Mantiene costante la lubrificazione, ricaricabile pi\u00f9 volte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SLOT GREASE\u00ae eroga il grasso in modo automatico in base alla richiesta del macchinario ed in funzione al tipo di molla, alla temperatura, al tipo di grasso NLGI e alle condizioni di esercizio. DURATA EROGAZIONE GRASSO: 1, 3, 6, 12 mesi. Contenitore da 220 ml&#8230;<\/p>\n","protected":false},"featured_media":10895,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_cat":[230,513,18,262],"product_tag":[],"class_list":["post-5952","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-fettschmierung-de","product_cat-schmierung-de","product_cat-senza-categoria","product_cat-automatischer-nachfullbarer-schmierstoffgeber-de","pa_fluid-ol-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ingrassatore automatico ricaricabile - F.lli Bonezzi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/bonezzi.it\/produkt\/ingrass-autom-ricaricabile-220-ml-per-olio\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ingrassatore automatico ricaricabile - F.lli Bonezzi\" \/>\n<meta property=\"og:description\" content=\"SLOT GREASE\u00ae eroga il grasso in modo automatico in base alla richiesta del macchinario ed in funzione al tipo di molla, alla temperatura, al tipo di grasso NLGI e alle condizioni di esercizio. DURATA EROGAZIONE GRASSO: 1, 3, 6, 12 mesi. Contenitore da 220 ml...\" \/>\n<meta property=\"og:url\" content=\"http:\/\/bonezzi.it\/produkt\/ingrass-autom-ricaricabile-220-ml-per-olio\/\" \/>\n<meta property=\"og:site_name\" content=\"F.lli Bonezzi\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-09T15:24:10+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/bonezzi.it\/wp-content\/uploads\/2022\/09\/681%20220A.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"1556\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/bonezzi.it\\\/produkt\\\/ingrass-autom-ricaricabile-220-ml-per-olio\\\/\",\"url\":\"http:\\\/\\\/bonezzi.it\\\/produkt\\\/ingrass-autom-ricaricabile-220-ml-per-olio\\\/\",\"name\":\"Ingrassatore automatico ricaricabile - F.lli Bonezzi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bonezzi.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/bonezzi.it\\\/produkt\\\/ingrass-autom-ricaricabile-220-ml-per-olio\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/bonezzi.it\\\/produkt\\\/ingrass-autom-ricaricabile-220-ml-per-olio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bonezzi.it\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/681 220A.jpg\",\"datePublished\":\"2022-09-29T12:55:16+00:00\",\"dateModified\":\"2024-04-09T15:24:10+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/bonezzi.it\\\/produkt\\\/ingrass-autom-ricaricabile-220-ml-per-olio\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/bonezzi.it\\\/produkt\\\/ingrass-autom-ricaricabile-220-ml-per-olio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"http:\\\/\\\/bonezzi.it\\\/produkt\\\/ingrass-autom-ricaricabile-220-ml-per-olio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bonezzi.it\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/681 220A.jpg\",\"contentUrl\":\"https:\\\/\\\/bonezzi.it\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/681 220A.jpg\",\"width\":720,\"height\":1556},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/bonezzi.it\\\/produkt\\\/ingrass-autom-ricaricabile-220-ml-per-olio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bonezzi.it\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Negozio\",\"item\":\"https:\\\/\\\/bonezzi.it\\\/de\\\/negozio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ingrassatore automatico ricaricabile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bonezzi.it\\\/#website\",\"url\":\"https:\\\/\\\/bonezzi.it\\\/\",\"name\":\"F.lli Bonezzi\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/bonezzi.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bonezzi.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bonezzi.it\\\/#organization\",\"name\":\"F.lli Bonezzi\",\"url\":\"https:\\\/\\\/bonezzi.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/bonezzi.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bonezzi.it\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/bonezzi.it\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo.svg\",\"width\":283,\"height\":105,\"caption\":\"F.lli Bonezzi\"},\"image\":{\"@id\":\"https:\\\/\\\/bonezzi.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ingrassatore automatico ricaricabile - F.lli Bonezzi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/bonezzi.it\/produkt\/ingrass-autom-ricaricabile-220-ml-per-olio\/","og_locale":"de_DE","og_type":"article","og_title":"Ingrassatore automatico ricaricabile - F.lli Bonezzi","og_description":"SLOT GREASE\u00ae eroga il grasso in modo automatico in base alla richiesta del macchinario ed in funzione al tipo di molla, alla temperatura, al tipo di grasso NLGI e alle condizioni di esercizio. DURATA EROGAZIONE GRASSO: 1, 3, 6, 12 mesi. Contenitore da 220 ml...","og_url":"http:\/\/bonezzi.it\/produkt\/ingrass-autom-ricaricabile-220-ml-per-olio\/","og_site_name":"F.lli Bonezzi","article_modified_time":"2024-04-09T15:24:10+00:00","og_image":[{"width":720,"height":1556,"url":"http:\/\/bonezzi.it\/wp-content\/uploads\/2022\/09\/681 220A.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/bonezzi.it\/produkt\/ingrass-autom-ricaricabile-220-ml-per-olio\/","url":"http:\/\/bonezzi.it\/produkt\/ingrass-autom-ricaricabile-220-ml-per-olio\/","name":"Ingrassatore automatico ricaricabile - F.lli Bonezzi","isPartOf":{"@id":"https:\/\/bonezzi.it\/#website"},"primaryImageOfPage":{"@id":"http:\/\/bonezzi.it\/produkt\/ingrass-autom-ricaricabile-220-ml-per-olio\/#primaryimage"},"image":{"@id":"http:\/\/bonezzi.it\/produkt\/ingrass-autom-ricaricabile-220-ml-per-olio\/#primaryimage"},"thumbnailUrl":"https:\/\/bonezzi.it\/wp-content\/uploads\/2022\/09\/681 220A.jpg","datePublished":"2022-09-29T12:55:16+00:00","dateModified":"2024-04-09T15:24:10+00:00","breadcrumb":{"@id":"http:\/\/bonezzi.it\/produkt\/ingrass-autom-ricaricabile-220-ml-per-olio\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["http:\/\/bonezzi.it\/produkt\/ingrass-autom-ricaricabile-220-ml-per-olio\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"http:\/\/bonezzi.it\/produkt\/ingrass-autom-ricaricabile-220-ml-per-olio\/#primaryimage","url":"https:\/\/bonezzi.it\/wp-content\/uploads\/2022\/09\/681 220A.jpg","contentUrl":"https:\/\/bonezzi.it\/wp-content\/uploads\/2022\/09\/681 220A.jpg","width":720,"height":1556},{"@type":"BreadcrumbList","@id":"http:\/\/bonezzi.it\/produkt\/ingrass-autom-ricaricabile-220-ml-per-olio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bonezzi.it\/de\/"},{"@type":"ListItem","position":2,"name":"Negozio","item":"https:\/\/bonezzi.it\/de\/negozio\/"},{"@type":"ListItem","position":3,"name":"Ingrassatore automatico ricaricabile"}]},{"@type":"WebSite","@id":"https:\/\/bonezzi.it\/#website","url":"https:\/\/bonezzi.it\/","name":"F.lli Bonezzi","description":"","publisher":{"@id":"https:\/\/bonezzi.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bonezzi.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/bonezzi.it\/#organization","name":"F.lli Bonezzi","url":"https:\/\/bonezzi.it\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/bonezzi.it\/#\/schema\/logo\/image\/","url":"https:\/\/bonezzi.it\/wp-content\/uploads\/2022\/05\/logo.svg","contentUrl":"https:\/\/bonezzi.it\/wp-content\/uploads\/2022\/05\/logo.svg","width":283,"height":105,"caption":"F.lli Bonezzi"},"image":{"@id":"https:\/\/bonezzi.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/bonezzi.it\/de\/wp-json\/wp\/v2\/product\/5952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bonezzi.it\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bonezzi.it\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bonezzi.it\/de\/wp-json\/wp\/v2\/media\/10895"}],"wp:attachment":[{"href":"https:\/\/bonezzi.it\/de\/wp-json\/wp\/v2\/media?parent=5952"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bonezzi.it\/de\/wp-json\/wp\/v2\/product_cat?post=5952"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bonezzi.it\/de\/wp-json\/wp\/v2\/product_tag?post=5952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}